{"id":2086,"date":"2023-07-23T18:34:11","date_gmt":"2023-07-23T18:34:11","guid":{"rendered":"https:\/\/statorials.org\/it\/quantile-di-panda-per-gruppo\/"},"modified":"2023-07-23T18:34:11","modified_gmt":"2023-07-23T18:34:11","slug":"quantile-di-panda-per-gruppo","status":"publish","type":"post","link":"https:\/\/statorials.org\/it\/quantile-di-panda-per-gruppo\/","title":{"rendered":"Come calcolare i quantili per gruppo in pandas"},"content":{"rendered":"<p><\/p>\n<hr>\n<p><span style=\"color: #000000;\">\u00c8 possibile utilizzare la seguente sintassi di base per calcolare i quantili per gruppo in Panda:<\/span><\/p>\n<pre style=\"background-color: #ececec; font-size: 15px;\"> <strong>df. <span style=\"color: #3366ff;\">groupby<\/span> (' <span style=\"color: #ff0000;\">grouping_variable<\/span> '). <span style=\"color: #3366ff;\">quantile<\/span> ( <span style=\"color: #008000;\">.5<\/span> )\n<\/strong><\/pre>\n<p> <span style=\"color: #000000;\">Gli esempi seguenti mostrano come utilizzare questa sintassi nella pratica.<\/span><\/p>\n<h3> <span style=\"color: #000000;\"><strong>Esempio 1: calcolare il quantile per gruppo<\/strong><\/span><\/h3>\n<p> <span style=\"color: #000000;\">Supponiamo di avere i seguenti panda DataFrame:<\/span><\/p>\n<pre style=\"background-color: #ececec; font-size: 15px;\"> <strong><span style=\"color: #008000;\">import<\/span> pandas <span style=\"color: #008000;\">as<\/span> pd\n\n<span style=\"color: #008080;\">#createDataFrame<\/span> \ndf = pd. <span style=\"color: #3366ff;\">DataFrame<\/span> ({' <span style=\"color: #ff0000;\">team<\/span> ': [1, 1, 1, 1, 1, 1, 2, 2, 2, 2, 2, 2],\n                   ' <span style=\"color: #ff0000;\">score<\/span> ': [3, 4, 4, 5, 5, 8, 1, 2, 2, 3, 3, 5]})\n\n<span style=\"color: #008080;\">#view first five rows<\/span>\ndf. <span style=\"color: #3366ff;\">head<\/span> ()\n\nteam score\n0 1 3\n1 1 4\n2 1 4\n3 1 5\n4 1 5 \n<\/strong><\/pre>\n<p> <span style=\"color: #000000;\">Il codice seguente mostra come calcolare il 90\u00b0 percentile dei valori nella colonna &#8220;punti&#8221;, raggruppati per la colonna &#8220;squadra&#8221;:<\/span><\/p>\n<pre style=\"background-color: #ececec; font-size: 15px;\"> <strong>df. <span style=\"color: #3366ff;\">groupby<\/span> (' <span style=\"color: #ff0000;\">team<\/span> '). <span style=\"color: #3366ff;\">quantile<\/span> ( <span style=\"color: #008000;\">.90<\/span> )\n\n\tscore\nteam\t\n1 6.5\n2 4.0\n<\/strong><\/pre>\n<p> <span style=\"color: #000000;\">Ecco come interpretare il risultato:<\/span><\/p>\n<ul>\n<li> <span style=\"color: #000000;\">Il 90\u00b0 percentile di \u201cpunti\u201d per la Squadra 1 \u00e8 <strong>6,5<\/strong> .<\/span><\/li>\n<li> <span style=\"color: #000000;\">Il 90\u00b0 percentile di \u201cpunti\u201d per la Squadra 2 \u00e8 <strong>4,0<\/strong> .<\/span><\/li>\n<\/ul>\n<h3> <span style=\"color: #000000;\"><strong>Esempio 2: calcolare pi\u00f9 quantili per gruppo<\/strong><\/span><\/h3>\n<p> <span style=\"color: #000000;\">Il codice seguente mostra come calcolare pi\u00f9 quantili contemporaneamente per gruppo:<\/span><\/p>\n<pre style=\"background-color: #ececec; font-size: 15px;\"> <strong><span style=\"color: #008000;\">import<\/span> pandas <span style=\"color: #008000;\">as<\/span> pd\n\n<span style=\"color: #008080;\">#createDataFrame<\/span>\ndf = pd. <span style=\"color: #3366ff;\">DataFrame<\/span> ({' <span style=\"color: #ff0000;\">team<\/span> ': [1, 1, 1, 1, 1, 1, 2, 2, 2, 2, 2, 2],\n                   ' <span style=\"color: #ff0000;\">score<\/span> ': [3, 4, 4, 5, 5, 8, 1, 2, 2, 3, 3, 5]})\n\n<span style=\"color: #008080;\">#create functions to calculate 1st and 3rd quartiles\n<\/span><span style=\"color: #008000;\">def<\/span> q1(x):\n    <span style=\"color: #008000;\">return<\/span> x. <span style=\"color: #3366ff;\">quantile<\/span> ( <span style=\"color: #008000;\">0.25<\/span> )\n\n<span style=\"color: #008000;\">def<\/span> q3(x):\n    <span style=\"color: #008000;\">return<\/span> x. <span style=\"color: #3366ff;\">quantile<\/span> ( <span style=\"color: #008000;\">0.75<\/span> )\n\n<span style=\"color: #008080;\">#calculate 1st and 3rd quartiles by group\n<\/span>vals = {' <span style=\"color: #ff0000;\">score<\/span> ': [q1, q3]}\n\ndf. <span style=\"color: #3366ff;\">groupby<\/span> (' <span style=\"color: #ff0000;\">team<\/span> '). <span style=\"color: #3366ff;\">agg<\/span> (vals)\n\n\tscore\n        q1 q3\nteam\t\t\n1 4.0 5.0\n2 2.0 3.0<\/strong><\/pre>\n<p> <span style=\"color: #000000;\">Ecco come interpretare il risultato:<\/span><\/p>\n<ul>\n<li> <span style=\"color: #000000;\">Il primo e il terzo quartile dei punteggi della squadra 1 sono rispettivamente <strong>4,0<\/strong> e <strong>5,0<\/strong> .<\/span><\/li>\n<li> <span style=\"color: #000000;\">Il primo e il terzo quartile dei punteggi della squadra 2 sono rispettivamente <strong>2,0<\/strong> e <strong>3,0<\/strong> .<\/span><\/li>\n<\/ul>\n<h3> <span style=\"color: #000000;\"><strong>Risorse addizionali<\/strong><\/span><\/h3>\n<p> <span style=\"color: #000000;\">I seguenti tutorial spiegano come eseguire altre funzioni comuni nei panda:<\/span><\/p>\n<p> <a href=\"https:\/\/statorials.org\/it\/massimo-per-gruppo-di-panda\/\" target=\"_blank\" rel=\"noopener\">Come trovare il valore massimo per gruppo su Pandas<\/a><br \/> <a href=\"https:\/\/statorials.org\/it\/gruppo-di-panda-per-numero\/\" target=\"_blank\" rel=\"noopener\">Come contare gli avvistamenti di gruppo nei panda<\/a><br \/> <a href=\"https:\/\/statorials.org\/it\/colonna-dei-panda-medi\/\" target=\"_blank\" rel=\"noopener\">Come calcolare la media delle colonne in Pandas<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 possibile utilizzare la seguente sintassi di base per calcolare i quantili per gruppo in Panda: df. groupby (&#8216; grouping_variable &#8216;). quantile ( .5 ) Gli esempi seguenti mostrano come utilizzare questa sintassi nella pratica. Esempio 1: calcolare il quantile per gruppo Supponiamo di avere i seguenti panda DataFrame: import pandas as pd #createDataFrame df [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Come calcolare i quantili di gruppo nei panda \u2013 Statorials<\/title>\n<meta name=\"description\" content=\"Questo tutorial spiega come calcolare i quantili di gruppo nei panda, con diversi esempi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/statorials.org\/it\/quantile-di-panda-per-gruppo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come calcolare i quantili di gruppo nei panda \u2013 Statorials\" \/>\n<meta property=\"og:description\" content=\"Questo tutorial spiega come calcolare i quantili di gruppo nei panda, con diversi esempi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/statorials.org\/it\/quantile-di-panda-per-gruppo\/\" \/>\n<meta property=\"og:site_name\" content=\"Statorials\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-23T18:34:11+00:00\" \/>\n<meta name=\"author\" content=\"Benjamin anderson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Benjamin anderson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/statorials.org\/it\/quantile-di-panda-per-gruppo\/\",\"url\":\"https:\/\/statorials.org\/it\/quantile-di-panda-per-gruppo\/\",\"name\":\"Come calcolare i quantili di gruppo nei panda \u2013 Statorials\",\"isPartOf\":{\"@id\":\"https:\/\/statorials.org\/it\/#website\"},\"datePublished\":\"2023-07-23T18:34:11+00:00\",\"dateModified\":\"2023-07-23T18:34:11+00:00\",\"author\":{\"@id\":\"https:\/\/statorials.org\/it\/#\/schema\/person\/0896f191fb9fb019f2cd8623112cb3ae\"},\"description\":\"Questo tutorial spiega come calcolare i quantili di gruppo nei panda, con diversi esempi.\",\"breadcrumb\":{\"@id\":\"https:\/\/statorials.org\/it\/quantile-di-panda-per-gruppo\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/statorials.org\/it\/quantile-di-panda-per-gruppo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/statorials.org\/it\/quantile-di-panda-per-gruppo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Casa\",\"item\":\"https:\/\/statorials.org\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come calcolare i quantili per gruppo in pandas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/statorials.org\/it\/#website\",\"url\":\"https:\/\/statorials.org\/it\/\",\"name\":\"Statorials\",\"description\":\"La tua guida all&#039;alfabetizzazione statistica!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/statorials.org\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/statorials.org\/it\/#\/schema\/person\/0896f191fb9fb019f2cd8623112cb3ae\",\"name\":\"Benjamin anderson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/statorials.org\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/statorials.org\/it\/wp-content\/uploads\/2023\/10\/Dr.-Benjamin-Anderson-96x96.jpg\",\"contentUrl\":\"https:\/\/statorials.org\/it\/wp-content\/uploads\/2023\/10\/Dr.-Benjamin-Anderson-96x96.jpg\",\"caption\":\"Benjamin anderson\"},\"description\":\"Ciao, sono Benjamin, un professore di statistica in pensione diventato insegnante dedicato di Statorials. Con una vasta esperienza e competenza nel campo della statistica, sono ansioso di condividere le mie conoscenze per potenziare gli studenti attraverso Statorials. Scopri di pi\u00f9\",\"sameAs\":[\"https:\/\/statorials.org\/it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come calcolare i quantili di gruppo nei panda \u2013 Statorials","description":"Questo tutorial spiega come calcolare i quantili di gruppo nei panda, con diversi esempi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/statorials.org\/it\/quantile-di-panda-per-gruppo\/","og_locale":"it_IT","og_type":"article","og_title":"Come calcolare i quantili di gruppo nei panda \u2013 Statorials","og_description":"Questo tutorial spiega come calcolare i quantili di gruppo nei panda, con diversi esempi.","og_url":"https:\/\/statorials.org\/it\/quantile-di-panda-per-gruppo\/","og_site_name":"Statorials","article_published_time":"2023-07-23T18:34:11+00:00","author":"Benjamin anderson","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Benjamin anderson","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/statorials.org\/it\/quantile-di-panda-per-gruppo\/","url":"https:\/\/statorials.org\/it\/quantile-di-panda-per-gruppo\/","name":"Come calcolare i quantili di gruppo nei panda \u2013 Statorials","isPartOf":{"@id":"https:\/\/statorials.org\/it\/#website"},"datePublished":"2023-07-23T18:34:11+00:00","dateModified":"2023-07-23T18:34:11+00:00","author":{"@id":"https:\/\/statorials.org\/it\/#\/schema\/person\/0896f191fb9fb019f2cd8623112cb3ae"},"description":"Questo tutorial spiega come calcolare i quantili di gruppo nei panda, con diversi esempi.","breadcrumb":{"@id":"https:\/\/statorials.org\/it\/quantile-di-panda-per-gruppo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/statorials.org\/it\/quantile-di-panda-per-gruppo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/statorials.org\/it\/quantile-di-panda-per-gruppo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Casa","item":"https:\/\/statorials.org\/it\/"},{"@type":"ListItem","position":2,"name":"Come calcolare i quantili per gruppo in pandas"}]},{"@type":"WebSite","@id":"https:\/\/statorials.org\/it\/#website","url":"https:\/\/statorials.org\/it\/","name":"Statorials","description":"La tua guida all&#039;alfabetizzazione statistica!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/statorials.org\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/statorials.org\/it\/#\/schema\/person\/0896f191fb9fb019f2cd8623112cb3ae","name":"Benjamin anderson","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/statorials.org\/it\/#\/schema\/person\/image\/","url":"https:\/\/statorials.org\/it\/wp-content\/uploads\/2023\/10\/Dr.-Benjamin-Anderson-96x96.jpg","contentUrl":"https:\/\/statorials.org\/it\/wp-content\/uploads\/2023\/10\/Dr.-Benjamin-Anderson-96x96.jpg","caption":"Benjamin anderson"},"description":"Ciao, sono Benjamin, un professore di statistica in pensione diventato insegnante dedicato di Statorials. Con una vasta esperienza e competenza nel campo della statistica, sono ansioso di condividere le mie conoscenze per potenziare gli studenti attraverso Statorials. Scopri di pi\u00f9","sameAs":["https:\/\/statorials.org\/it"]}]}},"yoast_meta":{"yoast_wpseo_title":"","yoast_wpseo_metadesc":"","yoast_wpseo_canonical":""},"_links":{"self":[{"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/posts\/2086"}],"collection":[{"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/comments?post=2086"}],"version-history":[{"count":0,"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/posts\/2086\/revisions"}],"wp:attachment":[{"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/media?parent=2086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/categories?post=2086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/tags?post=2086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}