{"id":2613,"date":"2023-07-21T12:23:47","date_gmt":"2023-07-21T12:23:47","guid":{"rendered":"https:\/\/statorials.org\/it\/sas-non-e-zero\/"},"modified":"2023-07-21T12:23:47","modified_gmt":"2023-07-21T12:23:47","slug":"sas-non-e-zero","status":"publish","type":"post","link":"https:\/\/statorials.org\/it\/sas-non-e-zero\/","title":{"rendered":"Sas: come selezionare osservazioni diverse da zero"},"content":{"rendered":"<p><\/p>\n<hr>\n<p><span style=\"color: #000000;\">\u00c8 possibile utilizzare la seguente sintassi di base per selezionare le osservazioni da un set di dati in SAS in cui un determinato valore di colonna non \u00e8 zero:<\/span><\/p>\n<pre style=\"background-color: #ececec; font-size: 15px;\"> <strong><span style=\"color: #008000;\">\/*select only rows where var1 is not null*\/\n<span style=\"color: #000000;\"><span style=\"color: #800080;\">proc sql<\/span> ;\n\t<span style=\"color: #3366ff;\">select<\/span> *\n\t<span style=\"color: #3366ff;\">from<\/span> my_data1\n\t<span style=\"color: #3366ff;\">where not<\/span> missing(var1);\n<span style=\"color: #800080;\">quit<\/span> ;<\/span><\/span><\/strong><\/pre>\n<p> <span style=\"color: #000000;\"><span style=\"color: #000000;\">L&#8217;esempio seguente mostra come utilizzare questa sintassi nella pratica.<\/span><\/span><\/p>\n<h3> <span style=\"color: #000000;\"><b>Esempio: selezionare le osservazioni che non sono zero in SAS<\/b><\/span><\/h3>\n<p> <span style=\"color: #000000;\">Supponiamo di avere il seguente set di dati in SAS:<\/span> <\/p>\n<pre style=\"background-color: #ececec; font-size: 15px;\"> <strong><span style=\"color: #008000;\">\/*create dataset*\/\n<span style=\"color: #000000;\"><span style=\"color: #800080;\">data<\/span> my_data1;\n    <span style=\"color: #3366ff;\">input<\/span> team $points;\n    <span style=\"color: #3366ff;\">datalines<\/span> ;\nAt 15\nB.\nC22\nD 19\nE29\nF.\nG 40\nH 35\n;\nrun;\n\n<span style=\"color: #008000;\">\/*view dataset*\/\n<\/span><span style=\"color: #800080;\">proc print<\/span> <span style=\"color: #3366ff;\">data<\/span> =my_data1;\n<\/span><\/span><\/strong><\/pre>\n<p><img decoding=\"async\" loading=\"lazy\" class=\" wp-image-23059 aligncenter\" src=\"https:\/\/statorials.org\/wp-content\/uploads\/2023\/08\/null1.jpg\" alt=\"\" width=\"151\" height=\"226\" srcset=\"\" sizes=\"\"><\/p>\n<p> <span style=\"color: #000000;\">Tieni presente che nella colonna <strong>dei punti<\/strong> sono presenti valori zero.<\/span><\/p>\n<p> <span style=\"color: #000000;\">Possiamo utilizzare il seguente codice per selezionare tutte le righe in cui il valore nella colonna <strong>dei punti<\/strong> non \u00e8 zero:<\/span> <\/p>\n<pre style=\"background-color: #ececec; font-size: 15px;\"> <strong><span style=\"color: #008000;\">\/*select only rows where points is not blank*\/\n<span style=\"color: #000000;\"><span style=\"color: #800080;\">proc sql<\/span> ;\n\t<span style=\"color: #3366ff;\">select<\/span> *\n\t<span style=\"color: #3366ff;\">from<\/span> my_data1\n\t<span style=\"color: #3366ff;\">where not<\/span> missing(points);\n<span style=\"color: #800080;\">quit<\/span> ;<\/span><\/span><\/strong> <\/pre>\n<p><img decoding=\"async\" loading=\"lazy\" class=\" wp-image-23060 aligncenter\" src=\"https:\/\/statorials.org\/wp-content\/uploads\/2023\/08\/nul2.jpg\" alt=\"\" width=\"123\" height=\"199\" srcset=\"\" sizes=\"\"><\/p>\n<p> <span style=\"color: #000000;\">Tieni presente che vengono restituite solo le righe il cui valore nella colonna <strong>dei punti<\/strong> non \u00e8 zero.<\/span><\/p>\n<p> <span style=\"color: #000000;\">Tieni presente che puoi anche utilizzare la funzione <strong>count()<\/strong> in <strong>proc sql<\/strong> per contare il numero di osservazioni in cui il valore nella colonna <strong>dei punti<\/strong> non \u00e8 zero:<\/span> <\/p>\n<pre style=\"background-color: #ececec; font-size: 15px;\"> <strong><span style=\"color: #008000;\">\/*count rows where points is not blank*\/\n<span style=\"color: #000000;\"><span style=\"color: #800080;\">proc sql<\/span> ;\n\t<span style=\"color: #3366ff;\">select<\/span> count(*)\n\t<span style=\"color: #3366ff;\">from<\/span> my_data1\n\t<span style=\"color: #3366ff;\">where not<\/span> missing(points);\n<span style=\"color: #800080;\">quit<\/span> ;<\/span><\/span><\/strong> <\/pre>\n<p><img decoding=\"async\" loading=\"lazy\" class=\" wp-image-23062 aligncenter\" src=\"https:\/\/statorials.org\/wp-content\/uploads\/2023\/08\/nul3.jpg\" alt=\"\" width=\"41\" height=\"65\" srcset=\"\" sizes=\"\"><\/p>\n<p> <span style=\"color: #000000;\">Questo ci dice che 6 osservazioni nel set di dati hanno un valore diverso da zero nella colonna <strong>dei punti<\/strong> .<\/span><\/p>\n<h3> <span style=\"color: #000000;\"><strong><span style=\"color: #000000;\">Risorse addizionali<\/span><\/strong><\/span><\/h3>\n<p> <span style=\"color: #000000;\">I seguenti tutorial spiegano come eseguire altre attivit\u00e0 comuni in SAS:<\/span><\/p>\n<p> <a href=\"https:\/\/statorials.org\/it\/normalizzare-i-dati-nella-camera-di-equilibrio\/\" target=\"_blank\" rel=\"noopener\">Come normalizzare i dati in SAS<\/a><br \/> <a href=\"https:\/\/statorials.org\/it\/sas-rinominare-le-variabili\/\" target=\"_blank\" rel=\"noopener\">Come rinominare le variabili in SAS<\/a><br \/> <a href=\"https:\/\/statorials.org\/it\/non-rimuovere-i-duplicati\/\" target=\"_blank\" rel=\"noopener\">Come rimuovere i duplicati in SAS<\/a><br \/> <a href=\"https:\/\/statorials.org\/it\/senza-sostituire-i-valori-mancanti-con-zero\/\" target=\"_blank\" rel=\"noopener\">Come sostituire i valori mancanti con zero in SAS<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 possibile utilizzare la seguente sintassi di base per selezionare le osservazioni da un set di dati in SAS in cui un determinato valore di colonna non \u00e8 zero: \/*select only rows where var1 is not null*\/ proc sql ; select * from my_data1 where not missing(var1); quit ; L&#8217;esempio seguente mostra come utilizzare questa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SAS: Come selezionare le osservazioni che non sono zero - Statorials<\/title>\n<meta name=\"description\" content=\"Questo tutorial spiega come selezionare osservazioni da un set di dati in SAS che non siano zero.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/statorials.org\/it\/sas-non-e-zero\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SAS: Come selezionare le osservazioni che non sono zero - Statorials\" \/>\n<meta property=\"og:description\" content=\"Questo tutorial spiega come selezionare osservazioni da un set di dati in SAS che non siano zero.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/statorials.org\/it\/sas-non-e-zero\/\" \/>\n<meta property=\"og:site_name\" content=\"Statorials\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-21T12:23:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/statorials.org\/wp-content\/uploads\/2023\/08\/null1.jpg\" \/>\n<meta name=\"author\" content=\"Benjamin anderson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Benjamin anderson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/statorials.org\/it\/sas-non-e-zero\/\",\"url\":\"https:\/\/statorials.org\/it\/sas-non-e-zero\/\",\"name\":\"SAS: Come selezionare le osservazioni che non sono zero - Statorials\",\"isPartOf\":{\"@id\":\"https:\/\/statorials.org\/it\/#website\"},\"datePublished\":\"2023-07-21T12:23:47+00:00\",\"dateModified\":\"2023-07-21T12:23:47+00:00\",\"author\":{\"@id\":\"https:\/\/statorials.org\/it\/#\/schema\/person\/0896f191fb9fb019f2cd8623112cb3ae\"},\"description\":\"Questo tutorial spiega come selezionare osservazioni da un set di dati in SAS che non siano zero.\",\"breadcrumb\":{\"@id\":\"https:\/\/statorials.org\/it\/sas-non-e-zero\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/statorials.org\/it\/sas-non-e-zero\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/statorials.org\/it\/sas-non-e-zero\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Casa\",\"item\":\"https:\/\/statorials.org\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sas: come selezionare osservazioni diverse da zero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/statorials.org\/it\/#website\",\"url\":\"https:\/\/statorials.org\/it\/\",\"name\":\"Statorials\",\"description\":\"La tua guida all&#039;alfabetizzazione statistica!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/statorials.org\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/statorials.org\/it\/#\/schema\/person\/0896f191fb9fb019f2cd8623112cb3ae\",\"name\":\"Benjamin anderson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/statorials.org\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/statorials.org\/it\/wp-content\/uploads\/2023\/10\/Dr.-Benjamin-Anderson-96x96.jpg\",\"contentUrl\":\"https:\/\/statorials.org\/it\/wp-content\/uploads\/2023\/10\/Dr.-Benjamin-Anderson-96x96.jpg\",\"caption\":\"Benjamin anderson\"},\"description\":\"Ciao, sono Benjamin, un professore di statistica in pensione diventato insegnante dedicato di Statorials. Con una vasta esperienza e competenza nel campo della statistica, sono ansioso di condividere le mie conoscenze per potenziare gli studenti attraverso Statorials. Scopri di pi\u00f9\",\"sameAs\":[\"https:\/\/statorials.org\/it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SAS: Come selezionare le osservazioni che non sono zero - Statorials","description":"Questo tutorial spiega come selezionare osservazioni da un set di dati in SAS che non siano zero.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/statorials.org\/it\/sas-non-e-zero\/","og_locale":"it_IT","og_type":"article","og_title":"SAS: Come selezionare le osservazioni che non sono zero - Statorials","og_description":"Questo tutorial spiega come selezionare osservazioni da un set di dati in SAS che non siano zero.","og_url":"https:\/\/statorials.org\/it\/sas-non-e-zero\/","og_site_name":"Statorials","article_published_time":"2023-07-21T12:23:47+00:00","og_image":[{"url":"https:\/\/statorials.org\/wp-content\/uploads\/2023\/08\/null1.jpg"}],"author":"Benjamin anderson","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Benjamin anderson","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/statorials.org\/it\/sas-non-e-zero\/","url":"https:\/\/statorials.org\/it\/sas-non-e-zero\/","name":"SAS: Come selezionare le osservazioni che non sono zero - Statorials","isPartOf":{"@id":"https:\/\/statorials.org\/it\/#website"},"datePublished":"2023-07-21T12:23:47+00:00","dateModified":"2023-07-21T12:23:47+00:00","author":{"@id":"https:\/\/statorials.org\/it\/#\/schema\/person\/0896f191fb9fb019f2cd8623112cb3ae"},"description":"Questo tutorial spiega come selezionare osservazioni da un set di dati in SAS che non siano zero.","breadcrumb":{"@id":"https:\/\/statorials.org\/it\/sas-non-e-zero\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/statorials.org\/it\/sas-non-e-zero\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/statorials.org\/it\/sas-non-e-zero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Casa","item":"https:\/\/statorials.org\/it\/"},{"@type":"ListItem","position":2,"name":"Sas: come selezionare osservazioni diverse da zero"}]},{"@type":"WebSite","@id":"https:\/\/statorials.org\/it\/#website","url":"https:\/\/statorials.org\/it\/","name":"Statorials","description":"La tua guida all&#039;alfabetizzazione statistica!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/statorials.org\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/statorials.org\/it\/#\/schema\/person\/0896f191fb9fb019f2cd8623112cb3ae","name":"Benjamin anderson","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/statorials.org\/it\/#\/schema\/person\/image\/","url":"https:\/\/statorials.org\/it\/wp-content\/uploads\/2023\/10\/Dr.-Benjamin-Anderson-96x96.jpg","contentUrl":"https:\/\/statorials.org\/it\/wp-content\/uploads\/2023\/10\/Dr.-Benjamin-Anderson-96x96.jpg","caption":"Benjamin anderson"},"description":"Ciao, sono Benjamin, un professore di statistica in pensione diventato insegnante dedicato di Statorials. Con una vasta esperienza e competenza nel campo della statistica, sono ansioso di condividere le mie conoscenze per potenziare gli studenti attraverso Statorials. Scopri di pi\u00f9","sameAs":["https:\/\/statorials.org\/it"]}]}},"yoast_meta":{"yoast_wpseo_title":"","yoast_wpseo_metadesc":"","yoast_wpseo_canonical":""},"_links":{"self":[{"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/posts\/2613"}],"collection":[{"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/comments?post=2613"}],"version-history":[{"count":0,"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/posts\/2613\/revisions"}],"wp:attachment":[{"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/media?parent=2613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/categories?post=2613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/tags?post=2613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}