{"id":841,"date":"2023-07-28T14:09:15","date_gmt":"2023-07-28T14:09:15","guid":{"rendered":"https:\/\/statorials.org\/it\/prova-pitone-mcnemars\/"},"modified":"2023-07-28T14:09:15","modified_gmt":"2023-07-28T14:09:15","slug":"prova-pitone-mcnemars","status":"publish","type":"post","link":"https:\/\/statorials.org\/it\/prova-pitone-mcnemars\/","title":{"rendered":"Come eseguire il test mcnemar in python"},"content":{"rendered":"<p><\/p>\n<hr>\n<p><span style=\"color: #000000;\"><strong>Il test McNemar<\/strong> viene utilizzato per determinare se esiste una differenza statisticamente significativa nelle proporzioni tra i dati accoppiati.<\/span><\/p>\n<p> <span style=\"color: #000000;\">Questo tutorial spiega come eseguire il test McNemar in Python.<\/span><\/p>\n<h3> <span style=\"color: #000000;\"><strong>Esempio: il test McNemar in Python<\/strong><\/span><\/h3>\n<p> <span style=\"color: #000000;\">Supponiamo che i ricercatori vogliano sapere se un determinato video di marketing pu\u00f2 cambiare le opinioni delle persone su una particolare legge. Intervistano 100 persone per scoprire se sostengono o meno la legge. Quindi mostrano il video di marketing a tutte le 100 persone e le esaminano nuovamente al termine del video.<\/span><\/p>\n<p> <span style=\"color: #000000;\">La tabella seguente mostra il numero totale di persone che hanno sostenuto la legge prima e dopo aver visto il video:<\/span><\/p>\n<table>\n<tbody>\n<tr>\n<th><\/th>\n<th colspan=\"2\"> <span style=\"color: #000000;\">Video prima della commercializzazione<\/span><\/th>\n<\/tr>\n<tr>\n<td> <span style=\"color: #000000;\">Video dopo la commercializzazione<\/span><\/td>\n<td> <span style=\"color: #000000;\"><strong>Supporto<\/strong><\/span><\/td>\n<td> <span style=\"color: #000000;\"><strong>Non sopporto<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td> <span style=\"color: #000000;\"><strong>Supporto<\/strong><\/span><\/td>\n<td> <span style=\"color: #000000;\">30<\/span><\/td>\n<td> <span style=\"color: #000000;\">40<\/span><\/td>\n<\/tr>\n<tr>\n<td> <span style=\"color: #000000;\"><strong>Non sopporto<\/strong><\/span><\/td>\n<td> <span style=\"color: #000000;\">12<\/span><\/td>\n<td> <span style=\"color: #000000;\">18<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <span style=\"color: #000000;\">Per determinare se ci fosse una differenza statisticamente significativa nella percentuale di persone che sostenevano la legge prima e dopo aver visto il video, possiamo eseguire il test McNemar.<\/span><\/p>\n<p> <span style=\"color: #000000;\"><strong>Passaggio 1: creare i dati.<\/strong><\/span><\/p>\n<p> <span style=\"color: #000000;\">Per prima cosa creeremo una tabella per contenere i nostri dati:<\/span><\/p>\n<pre style=\"background-color: #ececec; font-size: 15px;\"> <strong>data = [[30, 40],\n         [12, 18]]\n<\/strong><\/pre>\n<p> <span style=\"color: #000000;\"><strong>Passaggio 2: eseguire il test McNemar<\/strong><\/span><\/p>\n<p> <span style=\"color: #000000;\">Successivamente, possiamo utilizzare la <a href=\"https:\/\/www.statsmodels.org\/dev\/generated\/statsmodels.stats.contingency_tables.mcnemar.html\" target=\"_blank\" rel=\"noopener\">funzione mcnemar()<\/a> dalla libreria statsmodels di Python, che utilizza la seguente sintassi:<\/span><\/p>\n<p> <span style=\"color: #000000;\"><strong>mcnemar(array, esatto=Vero, correzione=Vero)<\/strong><\/span><\/p>\n<p> <span style=\"color: #000000;\">Oro:<\/span><\/p>\n<ul>\n<li> <span style=\"color: #000000;\"><strong>tabella:<\/strong> una tabella di contingenza quadrata<\/span><\/li>\n<li> <span style=\"color: #000000;\"><strong>esatto:<\/strong> se esatto \u00e8 vero, verr\u00e0 utilizzata la distribuzione binomiale. Se corretto \u00e8 falso, verr\u00e0 utilizzata la distribuzione Chi-quadrato<\/span><\/li>\n<li> <span style=\"color: #000000;\"><strong>correzione:<\/strong> se vero, viene utilizzata una correzione di continuit\u00e0. In genere, questa correzione viene applicata quando il numero di celle della tabella \u00e8 inferiore a 5.<\/span><\/li>\n<\/ul>\n<p> <span style=\"color: #000000;\">Il codice seguente mostra come utilizzare questa funzione nel nostro esempio specifico:<\/span><\/p>\n<pre style=\"background-color: #ececec; font-size: 15px;\"> <strong><span style=\"color: #008000;\">from<\/span> statsmodels.stats.contingency_tables <span style=\"color: #008000;\">import<\/span> mcnemar\n\n<span style=\"color: #008080;\">#McNemar's Test with no continuity correction<\/span>\nprint(mcnemar(data, exact=False))\n\npvalue 0.000181\nstatistic 14.019\n\n<span style=\"color: #008080;\">#McNemar's Test with continuity correction<\/span>\nprint(mcnemar(data, exact=False, correction=False))\n\npvalue 0.000103\nstatistic 15,077<\/strong><\/pre>\n<p> <span style=\"color: #000000;\">In entrambi i casi, indipendentemente dal fatto che venga applicata o meno la correzione di continuit\u00e0, il valore p del test \u00e8 inferiore a 0,05.<\/span><\/p>\n<p> <span style=\"color: #000000;\">Ci\u00f2 significa che in entrambi i casi rifiuteremmo l\u2019ipotesi nulla e concluderemmo che la percentuale di persone che sostenevano la legge prima e dopo aver visto il video di marketing era statisticamente diversa.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il test McNemar viene utilizzato per determinare se esiste una differenza statisticamente significativa nelle proporzioni tra i dati accoppiati. Questo tutorial spiega come eseguire il test McNemar in Python. Esempio: il test McNemar in Python Supponiamo che i ricercatori vogliano sapere se un determinato video di marketing pu\u00f2 cambiare le opinioni delle persone su una [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Come eseguire il test McNemar in Python - Statorials<\/title>\n<meta name=\"description\" content=\"Una semplice spiegazione su come eseguire il test McNemar in Python.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/statorials.org\/it\/prova-pitone-mcnemars\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come eseguire il test McNemar in Python - Statorials\" \/>\n<meta property=\"og:description\" content=\"Una semplice spiegazione su come eseguire il test McNemar in Python.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/statorials.org\/it\/prova-pitone-mcnemars\/\" \/>\n<meta property=\"og:site_name\" content=\"Statorials\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-28T14:09:15+00:00\" \/>\n<meta name=\"author\" content=\"Benjamin anderson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Benjamin anderson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/statorials.org\/it\/prova-pitone-mcnemars\/\",\"url\":\"https:\/\/statorials.org\/it\/prova-pitone-mcnemars\/\",\"name\":\"Come eseguire il test McNemar in Python - Statorials\",\"isPartOf\":{\"@id\":\"https:\/\/statorials.org\/it\/#website\"},\"datePublished\":\"2023-07-28T14:09:15+00:00\",\"dateModified\":\"2023-07-28T14:09:15+00:00\",\"author\":{\"@id\":\"https:\/\/statorials.org\/it\/#\/schema\/person\/0896f191fb9fb019f2cd8623112cb3ae\"},\"description\":\"Una semplice spiegazione su come eseguire il test McNemar in Python.\",\"breadcrumb\":{\"@id\":\"https:\/\/statorials.org\/it\/prova-pitone-mcnemars\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/statorials.org\/it\/prova-pitone-mcnemars\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/statorials.org\/it\/prova-pitone-mcnemars\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Casa\",\"item\":\"https:\/\/statorials.org\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come eseguire il test mcnemar in python\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/statorials.org\/it\/#website\",\"url\":\"https:\/\/statorials.org\/it\/\",\"name\":\"Statorials\",\"description\":\"La tua guida all&#039;alfabetizzazione statistica!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/statorials.org\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/statorials.org\/it\/#\/schema\/person\/0896f191fb9fb019f2cd8623112cb3ae\",\"name\":\"Benjamin anderson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/statorials.org\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/statorials.org\/it\/wp-content\/uploads\/2023\/10\/Dr.-Benjamin-Anderson-96x96.jpg\",\"contentUrl\":\"https:\/\/statorials.org\/it\/wp-content\/uploads\/2023\/10\/Dr.-Benjamin-Anderson-96x96.jpg\",\"caption\":\"Benjamin anderson\"},\"description\":\"Ciao, sono Benjamin, un professore di statistica in pensione diventato insegnante dedicato di Statorials. Con una vasta esperienza e competenza nel campo della statistica, sono ansioso di condividere le mie conoscenze per potenziare gli studenti attraverso Statorials. Scopri di pi\u00f9\",\"sameAs\":[\"https:\/\/statorials.org\/it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come eseguire il test McNemar in Python - Statorials","description":"Una semplice spiegazione su come eseguire il test McNemar in Python.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/statorials.org\/it\/prova-pitone-mcnemars\/","og_locale":"it_IT","og_type":"article","og_title":"Come eseguire il test McNemar in Python - Statorials","og_description":"Una semplice spiegazione su come eseguire il test McNemar in Python.","og_url":"https:\/\/statorials.org\/it\/prova-pitone-mcnemars\/","og_site_name":"Statorials","article_published_time":"2023-07-28T14:09:15+00:00","author":"Benjamin anderson","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Benjamin anderson","Est. reading time":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/statorials.org\/it\/prova-pitone-mcnemars\/","url":"https:\/\/statorials.org\/it\/prova-pitone-mcnemars\/","name":"Come eseguire il test McNemar in Python - Statorials","isPartOf":{"@id":"https:\/\/statorials.org\/it\/#website"},"datePublished":"2023-07-28T14:09:15+00:00","dateModified":"2023-07-28T14:09:15+00:00","author":{"@id":"https:\/\/statorials.org\/it\/#\/schema\/person\/0896f191fb9fb019f2cd8623112cb3ae"},"description":"Una semplice spiegazione su come eseguire il test McNemar in Python.","breadcrumb":{"@id":"https:\/\/statorials.org\/it\/prova-pitone-mcnemars\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/statorials.org\/it\/prova-pitone-mcnemars\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/statorials.org\/it\/prova-pitone-mcnemars\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Casa","item":"https:\/\/statorials.org\/it\/"},{"@type":"ListItem","position":2,"name":"Come eseguire il test mcnemar in python"}]},{"@type":"WebSite","@id":"https:\/\/statorials.org\/it\/#website","url":"https:\/\/statorials.org\/it\/","name":"Statorials","description":"La tua guida all&#039;alfabetizzazione statistica!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/statorials.org\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/statorials.org\/it\/#\/schema\/person\/0896f191fb9fb019f2cd8623112cb3ae","name":"Benjamin anderson","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/statorials.org\/it\/#\/schema\/person\/image\/","url":"https:\/\/statorials.org\/it\/wp-content\/uploads\/2023\/10\/Dr.-Benjamin-Anderson-96x96.jpg","contentUrl":"https:\/\/statorials.org\/it\/wp-content\/uploads\/2023\/10\/Dr.-Benjamin-Anderson-96x96.jpg","caption":"Benjamin anderson"},"description":"Ciao, sono Benjamin, un professore di statistica in pensione diventato insegnante dedicato di Statorials. Con una vasta esperienza e competenza nel campo della statistica, sono ansioso di condividere le mie conoscenze per potenziare gli studenti attraverso Statorials. Scopri di pi\u00f9","sameAs":["https:\/\/statorials.org\/it"]}]}},"yoast_meta":{"yoast_wpseo_title":"","yoast_wpseo_metadesc":"","yoast_wpseo_canonical":""},"_links":{"self":[{"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/posts\/841"}],"collection":[{"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/comments?post=841"}],"version-history":[{"count":0,"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/posts\/841\/revisions"}],"wp:attachment":[{"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/media?parent=841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/categories?post=841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/statorials.org\/it\/wp-json\/wp\/v2\/tags?post=841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}